{"id":10,"count":2,"description":"","link":"https:\/\/expoingenieria.edu.co\/en\/category\/boletines\/","name":"Boletines","slug":"boletines","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/expoingenieria.edu.co\/en\/wp-json\/wp\/v2\/categories\/10","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expoingenieria.edu.co\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/expoingenieria.edu.co\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/expoingenieria.edu.co\/en\/wp-json\/wp\/v2\/posts?categories=10"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}